{"id":1342,"date":"2014-09-02T23:35:45","date_gmt":"2014-09-02T23:35:45","guid":{"rendered":"http:\/\/sevillasemueve.org\/nocheenblanco2014\/museo-casa-de-la-ciencia-de-sevilla-consejo-superior-de-investigaciones-cientificas-csic\/"},"modified":"2014-09-28T13:32:27","modified_gmt":"2014-09-28T13:32:27","slug":"casa-de-la-ciencia","status":"publish","type":"post","link":"https:\/\/nocheenblanco.org\/2014\/casa-de-la-ciencia\/","title":{"rendered":"Museo Casa de la Ciencia de Sevilla. Consejo Superior de Investigaciones Cient\u00edficas (CSIC)"},"content":{"rendered":"<p>La Casa de la Ciencia de Sevilla es el museo donde la divulgaci\u00f3n del conocimiento de las instituciones p\u00fablicas de investigaci\u00f3n, especialmente cient\u00edfico y medio ambiental, se pone al servicio del ciudadano, de todas las edades, de una manera objetiva y rigurosa, pero tambi\u00e9n amena y atractiva para todos los p\u00fablicos.<\/p>\n<p>En concreto, quien se acerque durante la Noche en Blanco al edificio del Pabell\u00f3n de Per\u00fa de la Exposici\u00f3n Iberoamericana, podr\u00e1\u00a0acceder de forma gratuita y visitar las exposiciones permanentes del Museo (\u201cLa Mar de Cet\u00e1ceos en Andaluc\u00eda\u201d, \u201cInvertebrados de Andaluc\u00eda\u201d, \u201cGeo Sevilla: Explora 540 millones de a\u00f1os\u201d). Tambi\u00e9n podr\u00e1 ser visitada la exposici\u00f3n temporal \u201c\u00a1Eureka! Ciencia y creatividad\u201d, de la cual habr\u00e1 seis pases de visita guiada, uno cada hora de 20,00 a 01,00 horas. En cada pase podr\u00e1n participar 30 personas y ser\u00e1 necesaria una reserva previa a trav\u00e9s del tel\u00e9fono 954 23 23 49 o del correo electr\u00f3nico comunicacion.andalucia@csic.es. La programaci\u00f3n del espacio se completa con\u00a0la visita libre de la exposici\u00f3n \u00abCristales. Un mundo por descubrir\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Casa de la Ciencia de Sevilla es el museo donde la divulgaci\u00f3n del conocimiento de las instituciones p\u00fablicas de investigaci\u00f3n, especialmente cient\u00edfico y medio ambiental, se pone al servicio del ciudadano, de todas las edades, de una manera objetiva y rigurosa, pero tambi\u00e9n amena y atractiva para todos los  \u2026 <a href=\"https:\/\/nocheenblanco.org\/2014\/casa-de-la-ciencia\/\"> Continue reading <span class=\"meta-nav\">&rarr; <\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1622,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"aside","meta":{"_mi_skip_tracking":false},"categories":[40,19,34,3],"tags":[],"_links":{"self":[{"href":"https:\/\/nocheenblanco.org\/2014\/wp-json\/wp\/v2\/posts\/1342"}],"collection":[{"href":"https:\/\/nocheenblanco.org\/2014\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nocheenblanco.org\/2014\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nocheenblanco.org\/2014\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nocheenblanco.org\/2014\/wp-json\/wp\/v2\/comments?post=1342"}],"version-history":[{"count":2,"href":"https:\/\/nocheenblanco.org\/2014\/wp-json\/wp\/v2\/posts\/1342\/revisions"}],"predecessor-version":[{"id":1344,"href":"https:\/\/nocheenblanco.org\/2014\/wp-json\/wp\/v2\/posts\/1342\/revisions\/1344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nocheenblanco.org\/2014\/wp-json\/wp\/v2\/media\/1622"}],"wp:attachment":[{"href":"https:\/\/nocheenblanco.org\/2014\/wp-json\/wp\/v2\/media?parent=1342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nocheenblanco.org\/2014\/wp-json\/wp\/v2\/categories?post=1342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nocheenblanco.org\/2014\/wp-json\/wp\/v2\/tags?post=1342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}